{"id":6935,"date":"2023-07-23T06:35:07","date_gmt":"2023-07-23T06:35:07","guid":{"rendered":"https:\/\/www.wooshpay.com\/?p=6935"},"modified":"2024-01-29T08:27:25","modified_gmt":"2024-01-29T08:27:25","slug":"netflix-payment","status":"publish","type":"post","link":"https:\/\/wooshpay.com\/it\/resources\/knowledge\/online-payments\/2023\/07\/23\/netflix-payment\/","title":{"rendered":"Demistificare le opzioni di pagamento delle bollette: Netflix, elettricit\u00e0 BSES e bollette postpagate BSNL semplificati"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/Netflix-payment_01.jpg?x-oss-process=style\/webp\" alt=\"Pagamento Netflix\" \/><\/p>\n<p>Bene, ascoltate! Quando si tratta di pagare il vostro Netflix<a href=\"http:\/\/wooshpay.com\/it\/resources\/knowledge\/online-payments\/2024\/01\/26\/why-subscriptions-are-indispensable-for-consistent-business-revenue-streams\/\"> abbonamento,<\/a> hai delle opzioni, amico mio. Guarda qui:<\/p>\n<p class=\"translation-block\">Carta di credito o di debito: Conoscete la procedura. Accedete al vostro <a href=\"https:\/\/www.netflix.com\/\" target=\"_self\">account Netflix<\/a>, trovate la sezione \"Dettagli di fatturazione\" e aggiornate i dati di pagamento. \u00c8 possibile utilizzare tutte le principali carte di credito, come Visa, Mastercard, American Express e altre ancora.<\/p>\n<p><a href=\"http:\/\/www.paypal.com\">PayPal<\/a>: Se vi piace la vita di PayPal, siete fortunati. Collegate il vostro conto PayPal a Netflix e il gioco \u00e8 fatto! Basta accedere alla sezione \"Dettagli di fatturazione\", scegliere PayPal come metodo di pagamento e seguire i semplici passaggi.<\/p>\n<p class=\"translation-block\"><a href=\"https:\/\/www.netflix.com\/gift-cards\" target=\"_self\">Carta regalo Netflix<\/a>: Avete una carta regalo Netflix? Siete fortunati! Riscattatela sul sito web di Netflix o tramite l'app e il pagamento sar\u00e0 a carico del cliente. Si tratta di un regalo che continua a dare!<\/p>\n<p><a href=\"https:\/\/help.netflix.com\/en\/node\/116380\">Fatturazione del vettore mobile<\/a>: Questo dipende dal luogo in cui vi trovate e dal vostro operatore di telefonia mobile. Ma se \u00e8 un'opzione, potete addebitare il pagamento di Netflix direttamente sulla vostra bolletta telefonica mensile. A proposito di convenienza!<\/p>\n<p>Quindi, date un'occhiata a tutte queste opzioni di pagamento e scegliete quella pi\u00f9 adatta a voi. Netflix and chill, amico mio!<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/Bses-bill-payment_01.jpg?x-oss-process=style\/webp\" alt=\"Pagamento bollette Bses\" \/><\/p>\n<p>Ehi, ascoltate! Stiamo parlando del pagamento delle bollette BSES e, lasciatemelo dire, \u00e8 un gioco da ragazzi! Ecco come funziona, amici miei:<\/p>\n<p>Il pagamento delle bollette BSES consiste nel gestire la bolletta elettrica di BSES Rajdhani come un boss. Niente pi\u00f9 stress, niente pi\u00f9 preoccupazioni: bastano pochi clic e il gioco \u00e8 fatto!<\/p>\n<p>Come si fa? Facile facile! Ecco le istruzioni per sistemare la bolletta:<\/p>\n<ol>\n<li>Pagamento online: Questa \u00e8 la strada da seguire, amico mio. Collegatevi al sito web del BSES o utilizzate la sua applicazione mobile. Da l\u00ec, tutto fila liscio: basta inserire i dati della bolletta e scegliere il metodo di pagamento. Carta di credito, carta di debito, net banking... ci pensano loro!<\/li>\n<li>Opzioni offline: Se siete pi\u00f9 tipi da vecchia scuola, niente paura! Potete pagare presso i centri di pagamento BSES o i rivenditori autorizzati. Contanti o carta, va bene lo stesso!<\/li>\n<li>Programmare: Dimenticatevi di ricordare le scadenze! Impostate i pagamenti automatici e lasciate che la magia si compia. Bollette BSES pagate, senza problemi!<\/li>\n<\/ol>\n<p>Ecco una piccola cosa da tenere a mente: Pagate almeno qualche giorno prima della data di scadenza per evitare che le spese di mora vi colpiscano di sorpresa. Non lo vogliamo, giusto?<\/p>\n<p>Oh, e se vi state chiedendo delle spese, ecco come stanno le cose: a volte c'\u00e8 una piccola tassa di elaborazione (0,85% + GST) se il conto supera le 5.000 rupie. Non \u00e8 un problema, basta tenerlo a mente.<\/p>\n<p>E indovinate un po'? Potete effettuare fino a quattro transazioni al mese. Ma non fate un \"Charge back\" senza averne parlato con il personale di BSES Rajdhani. Sono loro che hanno tutte le risposte!<\/p>\n<p>Ecco a voi, amici miei! Il pagamento delle bollette BSES \u00e8 diventato facile, facile, facile! Tenete le luci accese e non preoccupatevi!<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/Bsnl-online-payment_01.jpg?x-oss-process=style\/webp\" alt=\"Pagamento online Bsnl\" \/><\/p>\n<p>Ricevuto! Stiamo parlando del pagamento del bollettino postale BSNL e sappiamo che avete delle domande. Non preoccupatevi, abbiamo le risposte pronte per voi! Controllate:<\/p>\n<ol>\n<li>Come controllare il pagamento della bolletta BSNL: Con MobiKwik \u00e8 un gioco da ragazzi! Basta inserire il vostro numero BSNL postpaid sul nostro sito web o sull'app. Cliccate sul pulsante di opzione postpaid, e bam! I dettagli della vostra bolletta BSNL sono davanti ai vostri occhi.<\/li>\n<li>Avete un problema? Ti copriamo le spalle! Se si presenta un problema con la vostra bolletta postpagata BSNL, avete delle opzioni. Rivolgetevi all'assistenza clienti BSNL o rivolgetevi direttamente a noi attraverso la sezione di assistenza sull'app o sul sito web MobiKwik. Siamo qui per risolvere il problema!<\/li>\n<li>Piani di pagamento della bolletta postpagata BSNL 4G: Li abbiamo tutti! Entrate in Mobikwik e godetevi i numerosi piani postpagati 4G di BSNL. Volete saperne di pi\u00f9? Chiamate il numero 24*7 e vi sveleremo tutti i dettagli del vostro piano.<\/li>\n<li>Rivolgetevi all'assistenza clienti di BSNL Postpaid: Sono a portata di mano! Chiamateli al numero 1800-425-1957. Oppure contattate la linea 24*7 per i dettagli del vostro piano.<\/li>\n<\/ol>\n<p>Ecco a voi, gente! Il pagamento delle bollette postpagate BSNL \u00e8 facile, veloce e senza stress! Risolvete le bollette e rimanete connessi con un sorriso!<\/p>","protected":false},"excerpt":{"rendered":"<p>Bene, ascoltate! Quando si tratta di pagare l'abbonamento a Netflix, hai delle opzioni, amico mio. Guarda un po': Carta di credito o di debito: Conoscete la procedura. Accedi al tuo account Netflix, trova la sezione \"Dettagli di fatturazione\" e aggiorna i dati di pagamento. Potete utilizzare tutte le principali carte di credito come Visa, Mastercard, American [...]<\/p>","protected":false},"author":5,"featured_media":6936,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[22],"tags":[103,104,40],"class_list":["post-6935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-online-payments","tag-credit-or-debit-card","tag-netflix-subscription-payment","tag-paypal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.8 (Yoast SEO v24.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Demystifying Bill Payment Options: Netflix, BSES Electricity, and BSNL Postpaid Bills Made Easy - WooshPay<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wooshpay.com\/it\/resources\/knowledge\/online-payments\/2023\/07\/23\/netflix-payment\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Demystifying Bill Payment Options: Netflix, BSES Electricity, and BSNL Postpaid Bills Made Easy\" \/>\n<meta property=\"og:description\" content=\"Alright, listen up! When it comes to paying for your Netflix subscription, you got options, my friend. Check it out: Credit or debit card: You know the drill. Log in to your Netflix account, find the &#8220;Billing Details&#8221; section, and update your payment info. You can use all those major cards like Visa, Mastercard, American [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wooshpay.com\/it\/resources\/knowledge\/online-payments\/2023\/07\/23\/netflix-payment\/\" \/>\n<meta property=\"og:site_name\" content=\"WooshPay\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-23T06:35:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-29T08:27:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/Netflix-payment_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"412\" \/>\n\t<meta property=\"og:image:height\" content=\"280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carmen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carmen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wooshpay.com\/fr\/resources\/knowledge\/paiements-en-ligne\/2023\/07\/23\/netflix-payment\/\",\"url\":\"https:\/\/wooshpay.com\/fr\/resources\/knowledge\/paiements-en-ligne\/2023\/07\/23\/netflix-payment\/\",\"name\":\"Demystifying Bill Payment Options: Netflix, BSES Electricity, and BSNL Postpaid Bills Made Easy - WooshPay\",\"isPartOf\":{\"@id\":\"https:\/\/wooshpay.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/wooshpay.com\/fr\/resources\/knowledge\/paiements-en-ligne\/2023\/07\/23\/netflix-payment\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/wooshpay.com\/fr\/resources\/knowledge\/paiements-en-ligne\/2023\/07\/23\/netflix-payment\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/Netflix-payment_01.jpg\",\"datePublished\":\"2023-07-23T06:35:07+00:00\",\"dateModified\":\"2024-01-29T08:27:25+00:00\",\"author\":{\"@id\":\"https:\/\/wooshpay.com\/fr\/#\/schema\/person\/d1e8b50ce9401cf26ad4e063a38c11e4\"},\"breadcrumb\":{\"@id\":\"https:\/\/wooshpay.com\/fr\/resources\/knowledge\/paiements-en-ligne\/2023\/07\/23\/netflix-payment\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wooshpay.com\/fr\/resources\/knowledge\/paiements-en-ligne\/2023\/07\/23\/netflix-payment\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/wooshpay.com\/fr\/resources\/knowledge\/paiements-en-ligne\/2023\/07\/23\/netflix-payment\/#primaryimage\",\"url\":\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/Netflix-payment_01.jpg\",\"contentUrl\":\"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/Netflix-payment_01.jpg\",\"width\":412,\"height\":280,\"caption\":\"Netflix payment\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wooshpay.com\/fr\/resources\/knowledge\/paiements-en-ligne\/2023\/07\/23\/netflix-payment\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/wooshpay.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Demystifying Bill Payment Options: Netflix, BSES Electricity, and BSNL Postpaid Bills Made Easy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wooshpay.com\/fr\/#website\",\"url\":\"https:\/\/wooshpay.com\/fr\/\",\"name\":\"WooshPay\",\"description\":\"One-stop payment platform\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wooshpay.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/wooshpay.com\/fr\/#\/schema\/person\/d1e8b50ce9401cf26ad4e063a38c11e4\",\"name\":\"Carmen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/wooshpay.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d0676f347bf6bab0695a958a8c355902b8deb007e7a59cf3a4cb0837da902583?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d0676f347bf6bab0695a958a8c355902b8deb007e7a59cf3a4cb0837da902583?s=96&d=mm&r=g\",\"caption\":\"Carmen\"},\"url\":\"https:\/\/wooshpay.com\/it\/author\/alyssa\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Demistificare le opzioni di pagamento delle bollette: Netflix, elettricit\u00e0 BSES e bollette postpagate BSNL semplificate - WooshPay","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wooshpay.com\/it\/resources\/knowledge\/online-payments\/2023\/07\/23\/netflix-payment\/","og_locale":"it_IT","og_type":"article","og_title":"Demystifying Bill Payment Options: Netflix, BSES Electricity, and BSNL Postpaid Bills Made Easy","og_description":"Alright, listen up! When it comes to paying for your Netflix subscription, you got options, my friend. Check it out: Credit or debit card: You know the drill. Log in to your Netflix account, find the &#8220;Billing Details&#8221; section, and update your payment info. You can use all those major cards like Visa, Mastercard, American [&hellip;]","og_url":"https:\/\/wooshpay.com\/it\/resources\/knowledge\/online-payments\/2023\/07\/23\/netflix-payment\/","og_site_name":"WooshPay","article_published_time":"2023-07-23T06:35:07+00:00","article_modified_time":"2024-01-29T08:27:25+00:00","og_image":[{"width":412,"height":280,"url":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/Netflix-payment_01.jpg","type":"image\/jpeg"}],"author":"Carmen","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Carmen","Est. reading time":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wooshpay.com\/fr\/resources\/knowledge\/paiements-en-ligne\/2023\/07\/23\/netflix-payment\/","url":"https:\/\/wooshpay.com\/fr\/resources\/knowledge\/paiements-en-ligne\/2023\/07\/23\/netflix-payment\/","name":"Demistificare le opzioni di pagamento delle bollette: Netflix, elettricit\u00e0 BSES e bollette postpagate BSNL semplificate - WooshPay","isPartOf":{"@id":"https:\/\/wooshpay.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wooshpay.com\/fr\/resources\/knowledge\/paiements-en-ligne\/2023\/07\/23\/netflix-payment\/#primaryimage"},"image":{"@id":"https:\/\/wooshpay.com\/fr\/resources\/knowledge\/paiements-en-ligne\/2023\/07\/23\/netflix-payment\/#primaryimage"},"thumbnailUrl":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/Netflix-payment_01.jpg","datePublished":"2023-07-23T06:35:07+00:00","dateModified":"2024-01-29T08:27:25+00:00","author":{"@id":"https:\/\/wooshpay.com\/fr\/#\/schema\/person\/d1e8b50ce9401cf26ad4e063a38c11e4"},"breadcrumb":{"@id":"https:\/\/wooshpay.com\/fr\/resources\/knowledge\/paiements-en-ligne\/2023\/07\/23\/netflix-payment\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wooshpay.com\/fr\/resources\/knowledge\/paiements-en-ligne\/2023\/07\/23\/netflix-payment\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/wooshpay.com\/fr\/resources\/knowledge\/paiements-en-ligne\/2023\/07\/23\/netflix-payment\/#primaryimage","url":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/Netflix-payment_01.jpg","contentUrl":"https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/Netflix-payment_01.jpg","width":412,"height":280,"caption":"Netflix payment"},{"@type":"BreadcrumbList","@id":"https:\/\/wooshpay.com\/fr\/resources\/knowledge\/paiements-en-ligne\/2023\/07\/23\/netflix-payment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wooshpay.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Demystifying Bill Payment Options: Netflix, BSES Electricity, and BSNL Postpaid Bills Made Easy"}]},{"@type":"WebSite","@id":"https:\/\/wooshpay.com\/fr\/#website","url":"https:\/\/wooshpay.com\/fr\/","name":"WooshPay","description":"Piattaforma di pagamento unica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wooshpay.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/wooshpay.com\/fr\/#\/schema\/person\/d1e8b50ce9401cf26ad4e063a38c11e4","name":"Carmen","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/wooshpay.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d0676f347bf6bab0695a958a8c355902b8deb007e7a59cf3a4cb0837da902583?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d0676f347bf6bab0695a958a8c355902b8deb007e7a59cf3a4cb0837da902583?s=96&d=mm&r=g","caption":"Carmen"},"url":"https:\/\/wooshpay.com\/it\/author\/alyssa\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/Netflix-payment_01.jpg",412,280,false],"thumbnail":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/Netflix-payment_01-150x150.jpg",150,150,true],"medium":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/Netflix-payment_01-300x204.jpg",300,204,true],"medium_large":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/Netflix-payment_01.jpg",412,280,false],"large":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/Netflix-payment_01.jpg",412,280,false],"1536x1536":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/Netflix-payment_01.jpg",412,280,false],"2048x2048":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/Netflix-payment_01.jpg",412,280,false],"trp-custom-language-flag":["https:\/\/wooshpay-official-img.oss-accelerate.aliyuncs.com\/wp-content\/uploads\/2023\/06\/Netflix-payment_01.jpg",18,12,false]},"uagb_author_info":{"display_name":"Carmen","author_link":"https:\/\/wooshpay.com\/it\/author\/alyssa\/"},"uagb_comment_info":0,"uagb_excerpt":"Alright, listen up! When it comes to paying for your Netflix subscription, you got options, my friend. Check it out: Credit or debit card: You know the drill. Log in to your Netflix account, find the &#8220;Billing Details&#8221; section, and update your payment info. You can use all those major cards like Visa, Mastercard, American&hellip;","_links":{"self":[{"href":"https:\/\/wooshpay.com\/it\/wp-json\/wp\/v2\/posts\/6935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wooshpay.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wooshpay.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wooshpay.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/wooshpay.com\/it\/wp-json\/wp\/v2\/comments?post=6935"}],"version-history":[{"count":0,"href":"https:\/\/wooshpay.com\/it\/wp-json\/wp\/v2\/posts\/6935\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wooshpay.com\/it\/wp-json\/wp\/v2\/media\/6936"}],"wp:attachment":[{"href":"https:\/\/wooshpay.com\/it\/wp-json\/wp\/v2\/media?parent=6935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wooshpay.com\/it\/wp-json\/wp\/v2\/categories?post=6935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wooshpay.com\/it\/wp-json\/wp\/v2\/tags?post=6935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}